{"id":803,"date":"2018-05-25T15:37:15","date_gmt":"2018-05-25T13:37:15","guid":{"rendered":"http:\/\/snl78.org\/?p=803"},"modified":"2018-05-25T15:38:16","modified_gmt":"2018-05-25T13:38:16","slug":"et-si-nous-donnions-un-nom-a-nos-nouveaux-locaux","status":"publish","type":"post","link":"https:\/\/snl78.org\/index.php\/2018\/05\/25\/et-si-nous-donnions-un-nom-a-nos-nouveaux-locaux\/","title":{"rendered":"Et si nous donnions un nom \u00e0 nos nouveaux locaux ?"},"content":{"rendered":"<p><img data-attachment-id=\"819\" data-permalink=\"https:\/\/snl78.org\/index.php\/2018\/05\/25\/et-si-nous-donnions-un-nom-a-nos-nouveaux-locaux\/dsc_0647\/\" data-orig-file=\"https:\/\/i0.wp.com\/snl78.org\/wp-content\/uploads\/2018\/05\/DSC_0647.jpg?fit=1024%2C685&amp;ssl=1\" data-orig-size=\"1024,685\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"DSC_0647\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/snl78.org\/wp-content\/uploads\/2018\/05\/DSC_0647.jpg?fit=300%2C201&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/snl78.org\/wp-content\/uploads\/2018\/05\/DSC_0647.jpg?fit=1024%2C685&amp;ssl=1\" loading=\"lazy\" class=\"alignleft wp-image-819 size-medium\" src=\"https:\/\/i1.wp.com\/snl78.org\/wp-content\/uploads\/2018\/05\/DSC_0647-300x201.jpg?resize=300%2C201\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/i0.wp.com\/snl78.org\/wp-content\/uploads\/2018\/05\/DSC_0647.jpg?resize=300%2C201&amp;ssl=1 300w, https:\/\/i0.wp.com\/snl78.org\/wp-content\/uploads\/2018\/05\/DSC_0647.jpg?resize=150%2C100&amp;ssl=1 150w, https:\/\/i0.wp.com\/snl78.org\/wp-content\/uploads\/2018\/05\/DSC_0647.jpg?resize=768%2C514&amp;ssl=1 768w, https:\/\/i0.wp.com\/snl78.org\/wp-content\/uploads\/2018\/05\/DSC_0647.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/snl78.org\/wp-content\/uploads\/2018\/05\/DSC_0647.jpg?resize=600%2C401&amp;ssl=1 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-recalc-dims=\"1\" \/><\/p>\n<p style=\"text-align: justify;\">Comment appeler nos nouveaux locaux ? La \u00ab\u00a0Maison SNL\u00a0\u00bb ? \u00ab\u00a0l&rsquo;Appart\u00a0\u00bb ou simplement \u00ab\u00a0Le Campus\u00a0\u00bb &#8230; Nous vous proposons d\u00e9j\u00e0 ces 3 noms &#8230; ils ne vous plaisent pas ? proposez en un autre !<\/p>\n<p style=\"text-align: justify;\">votez et faites voter !<\/p>\n<p>&nbsp;<\/p>\n<p>[democracy id=\u00a0\u00bb2&Prime;]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment appeler nos nouveaux locaux ? La \u00ab\u00a0Maison SNL\u00a0\u00bb ? \u00ab\u00a0l&rsquo;Appart\u00a0\u00bb ou simplement \u00ab\u00a0Le Campus\u00a0\u00bb &#8230; Nous vous proposons d\u00e9j\u00e0 ces 3 noms &#8230; ils ne vous plaisent pas ? proposez en un autre ! votez et faites voter ! &nbsp; [democracy id=\u00a0\u00bb2&Prime;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false},"categories":[17],"tags":[],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8nZxF-cX","jetpack-related-posts":[{"id":847,"url":"https:\/\/snl78.org\/index.php\/2018\/04\/29\/chronique-dun-demenagement\/","url_meta":{"origin":803,"position":0},"title":"Chronique d'un d\u00e9m\u00e9nagement !","date":"29 avril 2018","format":false,"excerpt":"Le 16 avril a vu se r\u00e9aliser ce que nous pr\u00e9parions depuis plusieurs mois et ce que certains souhaitaient depuis plusieurs ann\u00e9es\u00a0: l\u2019arriv\u00e9e de SNL Yvelines dans de nouveaux locaux\u00a0! Des locaux adapt\u00e9s, fonctionnels, agr\u00e9ables, permettant de bonnes conditions de travail pour les salari\u00e9s, d\u2019accueil pour les b\u00e9n\u00e9voles, locataires et\u2026","rel":"","context":"Dans &quot;Ev\u00e8nements&quot;","img":{"alt_text":"","src":"https:\/\/i2.wp.com\/snl78.org\/wp-content\/uploads\/2018\/05\/DSC_0628.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1245,"url":"https:\/\/snl78.org\/index.php\/2022\/03\/01\/expo-vente-13-au-17-avril-2022\/","url_meta":{"origin":803,"position":1},"title":"Expo vente 13 au 17 avril 2022","date":"1 mars 2022","format":false,"excerpt":"LE GROUPE LOCAL DE SAINT QUENTIN-EST\u00a0 DE SOLIDARIT\u00c9S NOUVELLES POUR LE LOGEMENT YVELINES ( S.N.L. Yvelines) Une belle exposition-vente d\u2019\u0153uvres d\u2019art vous est propos\u00e9e par notre groupe. Situ\u00e9e \u00e0 la maison F\u00e9lix, lieu d'exposition de Montigny-le-Bretonneux, elle se d\u00e9roulera du 13 au 17 avril 2022 Venez d\u00e9couvrir des artistes locaux\u2026","rel":"","context":"Dans &quot;Ev\u00e8nements&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":644,"url":"https:\/\/snl78.org\/index.php\/2018\/03\/20\/un-temps-de-partage-une-vraie-reussite\/","url_meta":{"origin":803,"position":2},"title":"Les ateliers, un temps de partage r\u00e9ussi !","date":"20 mars 2018","format":false,"excerpt":"\u00a0 Cr\u00e9er des projets, facteurs de liens, de rencontres, est toujours une belle aventure\u00a0! Une nouvelle initiative fin 2017 a vu le jour\u00a0: l'organisation de rencontres salari\u00e9s, b\u00e9n\u00e9voles et locataires. Convivialit\u00e9 au rendez-vous\u00a0! C\u2019est parti avec le Jeu KIJOULOU\u00a0! La premi\u00e8re initiative a eu lieu le 24 novembre 2017. Notre\u2026","rel":"","context":"Dans &quot;Ateliers&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/snl78.org\/wp-content\/uploads\/2018\/03\/photo1.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":988,"url":"https:\/\/snl78.org\/index.php\/2018\/10\/07\/samedi-17-novembre-nouvel-atelier-leco-c-quoi\/","url_meta":{"origin":803,"position":3},"title":"samedi 17 novembre : nouvel atelier \"L\u2018Eco C quoi ?\"","date":"7 octobre 2018","format":false,"excerpt":"A votre avis ? Comment \u00e9conomiser 100 \u20ac par personne et par an sur sa facture d\u2019eau ? Citez 3 produits naturels et pas chers pour nettoyer l\u2019ensemble de votre maison ? \u00a0 Pour avoir les r\u00e9ponses et plein de trucs et astuces, r\u00e9servez votre samedi 17 novembre, de 15h\u2026","rel":"","context":"Dans &quot;Ateliers&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1428,"url":"https:\/\/snl78.org\/index.php\/2025\/12\/29\/quand-lemballage-des-cadeaux-cree-du-lien\/","url_meta":{"origin":803,"position":4},"title":"Quand l\u2019emballage des cadeaux cr\u00e9e du lien","date":"29 d\u00e9cembre 2025","format":false,"excerpt":"Pendant deux semaines, b\u00e9n\u00e9voles et locataires de SNL Yvelines se sont relay\u00e9s au Furet du Nord pour emballer des cadeaux\u2026 et surtout pour aller \u00e0 la rencontre du public. Une op\u00e9ration solidaire, riche en \u00e9changes et en t\u00e9moignages, que nous vous invitons \u00e0 prolonger ici. Pendant 14 jours, b\u00e9n\u00e9voles, locataires\u2026","rel":"","context":"Dans &quot;Ev\u00e8nements&quot;","img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465,"url":"https:\/\/snl78.org\/index.php\/2026\/04\/02\/sous-les-etoiles-de-paris-au-chesnay\/","url_meta":{"origin":803,"position":5},"title":"Sous les \u00e9toiles de paris, au Chesnay","date":"2 avril 2026","format":false,"excerpt":"Catherine Frot, notre marraine, avec nous pour son film ! Prenez vos places, et venez voir ce film, mais aussi dialoguer avec Catherine Frot, qui nous fait l'amiti\u00e9 d'\u00eatre pr\u00e9sente.\u00a0 On peut donc joindre simplement l'utile et l'agr\u00e9able. soir\u00e9e unique. Prenez vos billets ici: (vous pouvez \u00eatre conduit vers le\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","img":{"alt_text":"","src":"https:\/\/i2.wp.com\/snl78.org\/wp-content\/uploads\/2026\/04\/catherine-Frot-e1775124857470.jpg?fit=600%2C644&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/snl78.org\/index.php\/wp-json\/wp\/v2\/posts\/803"}],"collection":[{"href":"https:\/\/snl78.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/snl78.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/snl78.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/snl78.org\/index.php\/wp-json\/wp\/v2\/comments?post=803"}],"version-history":[{"count":11,"href":"https:\/\/snl78.org\/index.php\/wp-json\/wp\/v2\/posts\/803\/revisions"}],"predecessor-version":[{"id":828,"href":"https:\/\/snl78.org\/index.php\/wp-json\/wp\/v2\/posts\/803\/revisions\/828"}],"wp:attachment":[{"href":"https:\/\/snl78.org\/index.php\/wp-json\/wp\/v2\/media?parent=803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/snl78.org\/index.php\/wp-json\/wp\/v2\/categories?post=803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/snl78.org\/index.php\/wp-json\/wp\/v2\/tags?post=803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}